{"id":35715,"date":"2024-03-07T10:23:31","date_gmt":"2024-03-07T15:23:31","guid":{"rendered":"https:\/\/qroo.gob.mx\/inicio\/?p=35715"},"modified":"2024-03-14T04:07:42","modified_gmt":"2024-03-14T09:07:42","slug":"se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad","status":"publish","type":"post","link":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/","title":{"rendered":"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad"},"content":{"rendered":"<p style=\"text-align: justify;\">-Durante 972 horas, 43 elementos se capacitaron en la Academia de Polic\u00eda y formar\u00e1n parte de la Secretar\u00eda de Seguridad Ciudadana<\/p>\n<p style=\"text-align: justify;\">Canc\u00fan.- Autoridades del Gobierno de Quintana Roo encabezaron la ceremonia de graduaci\u00f3n del Programa de Formaci\u00f3n Inicial de la Polic\u00eda Estatal Preventiva del que egresaron 43 elementos entre ellos 27 mujeres.<\/p>\n<p style=\"text-align: justify;\">Fue la explanada c\u00edvica del Complejo Estatal de Seguridad C-5 donde se realiz\u00f3 la ceremonia de graduaci\u00f3n de estos nuevos elementos que dedicaron 972 horas a un curso durante 5 meses que contempla 6 m\u00f3dulos y en el que adquirieron conocimientos, t\u00e9cnicas, t\u00e1cticas y habilidades para proteger a las y los quintanarroenses.<\/p>\n<p style=\"text-align: justify;\">La gobernadora del estado, Mara Lezama acompa\u00f1ada de los titulares y representantes de los poderes, de las instituciones del gobierno federal en materia de seguridad y de las corporaciones estatales y municipales, exhort\u00f3 los nuevos elementos a tener un buen desempe\u00f1o, pues ser polic\u00eda m\u00e1s que un trabajo, \u201ces un compromiso con la seguridad y el bienestar de los ciudadanos\u201d.<\/p>\n<p style=\"text-align: justify;\">El secretario de Seguridad Ciudadana Julio C\u00e9sar G\u00f3mez Torres, dijo a los egresados, antes de entregarles sus constancias, que el papel de la polic\u00eda es crucial, pues estar\u00e1n en la primera l\u00ednea de contacto para velar por la paz y la tranquilidad de las y los quintanarroenses.<\/p>\n<p style=\"text-align: justify;\">Los tres primeros promedios recibieron constancia, Paola Britany Uc, Anthony No\u00e9 Castellanos e Isela Ancona, quienes a nombre de sus compa\u00f1eras y compa\u00f1eros agradecieron a los instructores el haber compartido meses de retos y sacrificios.<\/p>\n<p style=\"text-align: justify;\">La Gobernadora estuvo acompa\u00f1ada de la presidenta municipal de Benito Ju\u00e1rez, Ana Paty Peralta de la Pe\u00f1a, quien tambi\u00e9n extendi\u00f3 felicitaciones a los graduados; el magistrado Heyden Cebada Rivas, presidente del Tribunal Superior de Justicia; la presidenta del Sistema DIF Quintana Roo, Ver\u00f3nica Lezama Espinosa; la secretaria de Gobierno Cristina Torres G\u00f3mez, as\u00ed como Jos\u00e9 de la Pe\u00f1a, coordinador del Gabinete de Seguridad del Estado.<\/p>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"35812\" src=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-1024x683.jpeg\" alt=\"\" class=\"wp-image-35812\" srcset=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-1024x683.jpeg 1024w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-300x200.jpeg 300w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-768x512.jpeg 768w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"35815\" src=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-2-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-35815\" srcset=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-2-1-1024x683.jpeg 1024w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-2-1-300x200.jpeg 300w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-2-1-768x512.jpeg 768w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-2-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"35814\" src=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-3-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-35814\" srcset=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-3-1-1024x576.jpeg 1024w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-3-1-300x169.jpeg 300w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-3-1-768x432.jpeg 768w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-3-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"35813\" src=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.43-1024x683.jpeg\" alt=\"\" class=\"wp-image-35813\" srcset=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.43-1024x683.jpeg 1024w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.43-300x200.jpeg 300w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.43-768x512.jpeg 768w, https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.43.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>-Durante 972 horas, 43 elementos se capacitaron en la Academia de Polic\u00eda y formar\u00e1n parte de la Secretar\u00eda de Seguridad Ciudadana Canc\u00fan.- Autoridades del Gobierno de Quintana Roo encabezaron la ceremonia de graduaci\u00f3n del Programa de Formaci\u00f3n Inicial de la Polic\u00eda Estatal Preventiva del que egresaron 43 elementos entre ellos 27 mujeres. Fue la explanada &#8230; <a title=\"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad\" class=\"read-more\" href=\"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/\" aria-label=\"Leer m\u00e1s sobre Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":35816,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-35715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad - Planetario Sayab Playa del Carmen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad - Planetario Sayab Playa del Carmen\" \/>\n<meta property=\"og:description\" content=\"-Durante 972 horas, 43 elementos se capacitaron en la Academia de Polic\u00eda y formar\u00e1n parte de la Secretar\u00eda de Seguridad Ciudadana Canc\u00fan.- Autoridades del Gobierno de Quintana Roo encabezaron la ceremonia de graduaci\u00f3n del Programa de Formaci\u00f3n Inicial de la Polic\u00eda Estatal Preventiva del que egresaron 43 elementos entre ellos 27 mujeres. Fue la explanada ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Planetario Sayab Playa del Carmen\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T15:23:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T09:07:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/\"},\"author\":{\"name\":\"Leonardo\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#\\\/schema\\\/person\\\/1955fadb670ba6bad4ebc54abcf1edd0\"},\"headline\":\"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad\",\"datePublished\":\"2024-03-07T15:23:31+00:00\",\"dateModified\":\"2024-03-14T09:07:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/\"},\"wordCount\":358,\"publisher\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/\",\"url\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/\",\"name\":\"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad - Planetario Sayab Playa del Carmen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg\",\"datePublished\":\"2024-03-07T15:23:31+00:00\",\"dateModified\":\"2024-03-14T09:07:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#website\",\"url\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/\",\"name\":\"Planetario Sayab Playa del Carmen\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#organization\",\"name\":\"Planetario Sayab Playa del Carmen\",\"url\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/COQCYT.png\",\"contentUrl\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/COQCYT.png\",\"width\":1920,\"height\":1080,\"caption\":\"Planetario Sayab Playa del Carmen\"},\"image\":{\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/#\\\/schema\\\/person\\\/1955fadb670ba6bad4ebc54abcf1edd0\",\"name\":\"Leonardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61478f61f78c5e2516f98d194623f5a7e3d19d58f206f69737cc6b2b443d0b93?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61478f61f78c5e2516f98d194623f5a7e3d19d58f206f69737cc6b2b443d0b93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61478f61f78c5e2516f98d194623f5a7e3d19d58f206f69737cc6b2b443d0b93?s=96&d=mm&r=g\",\"caption\":\"Leonardo\"},\"sameAs\":[\"http:\\\/\\\/10.1.194.80\\\/planetarioplaya\"],\"url\":\"https:\\\/\\\/planetarioplaya.qroo.gob.mx\\\/index.php\\\/author\\\/leonardogtz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad - Planetario Sayab Playa del Carmen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/","og_locale":"es_MX","og_type":"article","og_title":"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad - Planetario Sayab Playa del Carmen","og_description":"-Durante 972 horas, 43 elementos se capacitaron en la Academia de Polic\u00eda y formar\u00e1n parte de la Secretar\u00eda de Seguridad Ciudadana Canc\u00fan.- Autoridades del Gobierno de Quintana Roo encabezaron la ceremonia de graduaci\u00f3n del Programa de Formaci\u00f3n Inicial de la Polic\u00eda Estatal Preventiva del que egresaron 43 elementos entre ellos 27 mujeres. Fue la explanada ... Leer m\u00e1s","og_url":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/","og_site_name":"Planetario Sayab Playa del Carmen","article_published_time":"2024-03-07T15:23:31+00:00","article_modified_time":"2024-03-14T09:07:42+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg","type":"image\/jpeg"}],"author":"Leonardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/#article","isPartOf":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/"},"author":{"name":"Leonardo","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#\/schema\/person\/1955fadb670ba6bad4ebc54abcf1edd0"},"headline":"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad","datePublished":"2024-03-07T15:23:31+00:00","dateModified":"2024-03-14T09:07:42+00:00","mainEntityOfPage":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/"},"wordCount":358,"publisher":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#organization"},"image":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/","url":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/","name":"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad - Planetario Sayab Playa del Carmen","isPartOf":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/#primaryimage"},"image":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg","datePublished":"2024-03-07T15:23:31+00:00","dateModified":"2024-03-14T09:07:42+00:00","breadcrumb":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/#primaryimage","url":"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg","contentUrl":"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.15.42-1-1.jpeg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/se-gradua-nueva-generacion-de-elementos-estatales-para-sumarse-a-la-estrategia-de-construccion-de-la-paz-y-la-seguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/planetarioplaya.qroo.gob.mx\/"},{"@type":"ListItem","position":2,"name":"Se grad\u00faa nueva generaci\u00f3n de elementos estatales para sumarse a la estrategia de construcci\u00f3n de la paz y la seguridad"}]},{"@type":"WebSite","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#website","url":"https:\/\/planetarioplaya.qroo.gob.mx\/","name":"Planetario Sayab Playa del Carmen","description":"","publisher":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planetarioplaya.qroo.gob.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#organization","name":"Planetario Sayab Playa del Carmen","url":"https:\/\/planetarioplaya.qroo.gob.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#\/schema\/logo\/image\/","url":"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/08\/COQCYT.png","contentUrl":"https:\/\/planetarioplaya.qroo.gob.mx\/wp-content\/uploads\/2024\/08\/COQCYT.png","width":1920,"height":1080,"caption":"Planetario Sayab Playa del Carmen"},"image":{"@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/planetarioplaya.qroo.gob.mx\/#\/schema\/person\/1955fadb670ba6bad4ebc54abcf1edd0","name":"Leonardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/61478f61f78c5e2516f98d194623f5a7e3d19d58f206f69737cc6b2b443d0b93?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61478f61f78c5e2516f98d194623f5a7e3d19d58f206f69737cc6b2b443d0b93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61478f61f78c5e2516f98d194623f5a7e3d19d58f206f69737cc6b2b443d0b93?s=96&d=mm&r=g","caption":"Leonardo"},"sameAs":["http:\/\/10.1.194.80\/planetarioplaya"],"url":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/author\/leonardogtz\/"}]}},"_links":{"self":[{"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/35715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/comments?post=35715"}],"version-history":[{"count":1,"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/35715\/revisions"}],"predecessor-version":[{"id":35817,"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/35715\/revisions\/35817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/media\/35816"}],"wp:attachment":[{"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/media?parent=35715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/categories?post=35715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/planetarioplaya.qroo.gob.mx\/index.php\/wp-json\/wp\/v2\/tags?post=35715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}